{"id":44930,"date":"2022-05-09T08:33:17","date_gmt":"2022-05-09T08:33:17","guid":{"rendered":"https:\/\/www.policlinicogemelli.it\/news-eventi\/fibrosi-polmonare-idiopatica-vaccini-anti-covid-potrebbero-scatenare-una-riacutizzazione\/"},"modified":"2022-05-09T08:33:19","modified_gmt":"2022-05-09T08:33:19","slug":"fibrosi-polmonare-idiopatica-vaccini-anti-covid-potrebbero-scatenare-una-riacutizzazione","status":"publish","type":"kf_gem_news","link":"https:\/\/www.policlinicogemelli.it\/en\/news-events\/fibrosi-polmonare-idiopatica-vaccini-anti-covid-potrebbero-scatenare-una-riacutizzazione\/","title":{"rendered":"Fibrosi polmonare idiopatica, vaccini anti-Covid potrebbero scatenare una riacutizzazione"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Uno studio descrittivo effettuato al Gemelli e pubblicato su American Journal of Respiratory and Critical Care Medicine segnala un rapporto temporale tra vaccinazione anti-Covid e gravi episodi di riacutizzazione, verificatisi nei 3-5 giorni successivi, nei soggetti affetti da questa malattia rara. Gli esperti invitano dunque a monitorare con attenzione questi pazienti, pur ribadendo l\u2019assoluta necessit\u00e0 di sottoporli a vaccinazione<\/em><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dallo scorso anno, la vita di tutti \u00e8 cambiata grazie all\u2019introduzione dei vaccini anti-Covid, dei quali \u00e8 stata garantita la priorit\u00e0 di accesso alle persone pi\u00f9 fragili che, in caso di infezione da SARS-CoV-2, avrebbero le conseguenze peggiori. Tra queste, quelle con fibrosi polmonare idiopatica (IPF) una malattia rara, dalla prognosi impegnativa. Si stima che a essere affette da questa condizione in Italia possano essere circa 30-50.000 persone. La malattia progredisce gradualmente con sviluppo di insufficienza respiratoria, e il suo decorso pu\u00f2 essere caratterizzato da momenti di crisi gravi, dette esacerbazioni (o riacutizzazioni), che sono gravate di una mortalit\u00e0 intraospedaliera dal 50 all\u201980%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa IPF \u2013 spiega il professor <strong>Luca Richeldi<\/strong>, direttore della UOC di Pneumologia della Fondazione Policlinico Universitario Agostino Gemelli IRCCS e Ordinario di Pneumologia dell\u2019Universit\u00e0 Cattolica del Sacro Cuore, campus di Roma &#8211; \u00e8 caratterizzata da aggravamenti acuti delle condizioni cliniche, che sono a loro volta idiopatici; in alcuni casi sono stati collegati a una causa infettiva o a una trombo-embolia polmonare; le vere forme di riacutizzazione acuta di malattia hanno una mortalit\u00e0 fino all\u201980% e rappresentano la principale causa di morte di questi pazienti, che peggiorano rapidamente nell\u2019arco di qualche settimana. Non c\u2019\u00e8 una terapia specifica; vengono utilizzati corticosteroidi ad alte dosi, con risultati abbastanza scarsi. Si tratta di eventi catastrofici che \u00e8 bene intercettare tempestivamente. Tutti i nostri 300 pazienti sono allertati sul fatto che un peggioramento rapido dei sintomi richiede un\u2019allerta precoce al medico curante o l\u2019invio in pronto soccorso\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cos\u00ec come non \u00e8 nota l\u2019eziologia dell\u2019IPF, allo stesso modo non si conoscono le cause scatenanti delle esacerbazioni, anche se si annoverano tra i fattori di rischio le infezioni virali, l\u2019esposizione a tossici ambientali e a polveri. Uno studio appena pubblicato su AJRCCM (<em>American Journal of Respiratory and Critical Care Medicine<\/em>) dal dottor <strong>Giacomo Sgalla<\/strong>, dal professor Luca Richeldi e colleghi della UOC di Pneumologia della Fondazione Policlinico Universitario Agostino Gemelli IRCCS, aggiunge per\u00f2 un\u2019importante informazione. Su 10 pazienti ricoverati nel 2021 per un episodio di esacerbazione nell\u2019ambito di una fibrosi polmonare idiopatica, presso la Fondazione Policlinico Gemelli, che \u00e8 uno dei pi\u00f9 importanti centri di riferimento in Italia per questa patologia, quattro presentavano un rapporto temporale con la somministrazione di un vaccino a mRNA anti-Covid, avvenuta qualche giorno prima dell\u2019episodio. In un paziente l\u2019episodio di esacerbazione si \u00e8 verificato dopo la prima dose, in uno dopo la seconda dose e nei restanti due dopo la dose booster. \u201cLa vicinanza temporale tra somministrazione del vaccino (effettuato tra 3 e 5 giorni prima) e l\u2019inizio dei sintomi \u2013 commenta il dottor Sgalla &#8211; indica il vaccino anti-Covid come il pi\u00f9 probabile<em> trigger<\/em> dell\u2019esacerbazione acuta\u201d. Al momento del ricovero questi pazienti presentavano indici di infiammazione elevati; alla TAC era evidente un impegno diffuso dell\u2019interstizio polmonare. Tutti sono stati sottoposti a trattamento con alti flussi di ossigeno e ad elevate dosi di cortisonici. Nonostante la tempestiva terapia due di questi pazienti sono deceduti durante il ricovero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cIn questo studio \u2013 prosegue Sgalla \u2013 abbiamo descritto un evento raro verificatosi nell\u2019ambito di una patologia rara; nel nostro centro seguiamo oltre 300 pazienti con IPF, che sono stati tutti sottoposti a vaccinazione anti-Covid. Solo quattro di loro sono stati ricoverati per una riacutizzazione a distanza di pochi giorni dalla vaccinazione anti- Covid. Queste riacutizzazioni dopo vaccino non sembrano presentare caratteristiche peculiari. \u00c8 possibile che in alcuni di questi pazienti, la liberazione di citochine infiammatorie, causata dalla vaccinazione, possa aver fatto da innesco di questa esacerbazione acuta. Nelle linee guida internazionali sulla IPF ad oggi le vaccinazioni non sono elencate tra i fattori di rischio delle esacerbazioni. Tuttavia, considerato che casi simili, anch\u2019essi molto rari, sono stati segnalati anche dopo vaccinazione antinfluenzale H1N1, suggeriamo di inserire nella lista dei possibili fattori di rischio per riacutizzazioni di IPF anche le vaccinazioni anti-virali\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLo scorso anno \u2013conclude il professor Richeldi &#8211; tra i pazienti riacutizzati ricoverati nel nostro centro, abbiamo individuato un piccolo numero di casi, accomunati dal fatto di aver effettuato di recente la vaccinazione anti-Covid. Non si tratta certo di una dimostrazione di causa-effetto, ma di una correlazione temporale che abbiamo voluto segnalare per due motivi. Il primo \u00e8 che i vaccini a mRNA anti-Covid sono vaccini nuovi, che noi suggeriamo di annoverare tra le potenziali cause di una riacutizzazione. L\u2019altro \u00e8 per allertare i medici che seguono questi pazienti del fatto che c\u2019\u00e8 una possibilit\u00e0, anche se molto remota, che il vaccino possa scatenare una riacutizzazione. Ribadiamo tuttavia la necessit\u00e0 che questi pazienti effettuino, e in modo prioritario, la vaccinazione anti-Covid; perch\u00e9 un\u2019eventuale polmonite interstiziale da Covid, su un paziente che ha gi\u00e0 una patologia interstiziale come la IPF, pu\u00f2 avere effetti catastrofici. Quindi in conclusione, il rapporto costo-beneficio rimane largamente in favore della vaccinazione anti-Covid e del ciclo completo (3 dosi complete o 4 per chi ha superato gli 80 anni). Sapere che esiste la possibilit\u00e0 di una riacutizzazione \u00e8 un\u2019informazione in pi\u00f9 che abbiamo oggi. Questi pazienti vanno sorvegliati strettamente soprattutto nelle prime due settimane dopo la vaccinazione, anche da remoto, con un approccio di teleassistenza (tele-saturimetria), per evidenziare tempestivamente delle desaturazioni delle quali magari il paziente non percepisce subito la portata, ma che sono importanti\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Maria Rita Montebelli<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno studio descrittivo effettuato al Gemelli e pubblicato su American Journal of Respiratory and Critical Care Medicine segnala un rapporto temporale tra vaccinazione anti-Covid e gravi episodi di riacutizzazione, verificatisi nei 3-5 giorni successivi, nei soggetti affetti da questa malattia rara. Gli esperti invitano dunque a monitorare con attenzione questi pazienti, pur ribadendo l\u2019assoluta necessit\u00e0 [&hellip;]<\/p>\n","protected":false},"featured_media":44928,"template":"","categorie":[95],"class_list":["post-44930","kf_gem_news","type-kf_gem_news","status-publish","has-post-thumbnail","kf_gem_newscat-research","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fibrosi polmonare idiopatica, vaccini anti-Covid potrebbero scatenare una riacutizzazione - Policlinico Universitario A. Gemelli IRCCS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.policlinicogemelli.it\/en\/news-events\/fibrosi-polmonare-idiopatica-vaccini-anti-covid-potrebbero-scatenare-una-riacutizzazione\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fibrosi polmonare idiopatica, vaccini anti-Covid potrebbero scatenare una riacutizzazione - Policlinico Universitario A. Gemelli IRCCS\" \/>\n<meta property=\"og:description\" content=\"Uno studio descrittivo effettuato al Gemelli e pubblicato su American Journal of Respiratory and Critical Care Medicine segnala un rapporto temporale tra vaccinazione anti-Covid e gravi episodi di riacutizzazione, verificatisi nei 3-5 giorni successivi, nei soggetti affetti da questa malattia rara. Gli esperti invitano dunque a monitorare con attenzione questi pazienti, pur ribadendo l\u2019assoluta necessit\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.policlinicogemelli.it\/en\/news-events\/fibrosi-polmonare-idiopatica-vaccini-anti-covid-potrebbero-scatenare-una-riacutizzazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Policlinico Universitario Agostino Gemelli IRCCS\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-09T08:33:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.policlinicogemelli.it\/wp-content\/uploads\/2022\/05\/Giacomo-Sgalla-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.policlinicogemelli.it\\\/en\\\/news-events\\\/fibrosi-polmonare-idiopatica-vaccini-anti-covid-potrebbero-scatenare-una-riacutizzazione\\\/\",\"url\":\"https:\\\/\\\/www.policlinicogemelli.it\\\/en\\\/news-events\\\/fibrosi-polmonare-idiopatica-vaccini-anti-covid-potrebbero-scatenare-una-riacutizzazione\\\/\",\"name\":\"Fibrosi polmonare idiopatica, vaccini anti-Covid potrebbero scatenare una riacutizzazione - Policlinico Universitario A. Gemelli IRCCS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.policlinicogemelli.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.policlinicogemelli.it\\\/en\\\/news-events\\\/fibrosi-polmonare-idiopatica-vaccini-anti-covid-potrebbero-scatenare-una-riacutizzazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.policlinicogemelli.it\\\/en\\\/news-events\\\/fibrosi-polmonare-idiopatica-vaccini-anti-covid-potrebbero-scatenare-una-riacutizzazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.policlinicogemelli.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Giacomo-Sgalla-2.jpg\",\"datePublished\":\"2022-05-09T08:33:17+00:00\",\"dateModified\":\"2022-05-09T08:33:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.policlinicogemelli.it\\\/en\\\/news-events\\\/fibrosi-polmonare-idiopatica-vaccini-anti-covid-potrebbero-scatenare-una-riacutizzazione\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.policlinicogemelli.it\\\/en\\\/news-events\\\/fibrosi-polmonare-idiopatica-vaccini-anti-covid-potrebbero-scatenare-una-riacutizzazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.policlinicogemelli.it\\\/en\\\/news-events\\\/fibrosi-polmonare-idiopatica-vaccini-anti-covid-potrebbero-scatenare-una-riacutizzazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.policlinicogemelli.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Giacomo-Sgalla-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.policlinicogemelli.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Giacomo-Sgalla-2.jpg\",\"width\":4000,\"height\":2250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.policlinicogemelli.it\\\/en\\\/news-events\\\/fibrosi-polmonare-idiopatica-vaccini-anti-covid-potrebbero-scatenare-una-riacutizzazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.policlinicogemelli.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News and Events\",\"item\":\"https:\\\/\\\/www.policlinicogemelli.it\\\/en\\\/news-events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fibrosi polmonare idiopatica, vaccini anti-Covid potrebbero scatenare una riacutizzazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.policlinicogemelli.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.policlinicogemelli.it\\\/en\\\/\",\"name\":\"Policlinico Universitario Agostino Gemelli IRCCS\",\"description\":\"Policlinico Universitario Agostino Gemelli IRCCS\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.policlinicogemelli.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.policlinicogemelli.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.policlinicogemelli.it\\\/en\\\/#organization\",\"name\":\"Policlinico Universitario Agostino Gemelli IRCCS\",\"url\":\"https:\\\/\\\/www.policlinicogemelli.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.policlinicogemelli.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.policlinicogemelli.it\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/logo-policlinico-gemelli-250-trasp-color-1.png\",\"contentUrl\":\"https:\\\/\\\/www.policlinicogemelli.it\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/logo-policlinico-gemelli-250-trasp-color-1.png\",\"width\":250,\"height\":82,\"caption\":\"Policlinico Universitario Agostino Gemelli IRCCS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.policlinicogemelli.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fibrosi polmonare idiopatica, vaccini anti-Covid potrebbero scatenare una riacutizzazione - Policlinico Universitario A. Gemelli IRCCS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.policlinicogemelli.it\/en\/news-events\/fibrosi-polmonare-idiopatica-vaccini-anti-covid-potrebbero-scatenare-una-riacutizzazione\/","og_locale":"en_US","og_type":"article","og_title":"Fibrosi polmonare idiopatica, vaccini anti-Covid potrebbero scatenare una riacutizzazione - Policlinico Universitario A. Gemelli IRCCS","og_description":"Uno studio descrittivo effettuato al Gemelli e pubblicato su American Journal of Respiratory and Critical Care Medicine segnala un rapporto temporale tra vaccinazione anti-Covid e gravi episodi di riacutizzazione, verificatisi nei 3-5 giorni successivi, nei soggetti affetti da questa malattia rara. Gli esperti invitano dunque a monitorare con attenzione questi pazienti, pur ribadendo l\u2019assoluta necessit\u00e0 [&hellip;]","og_url":"https:\/\/www.policlinicogemelli.it\/en\/news-events\/fibrosi-polmonare-idiopatica-vaccini-anti-covid-potrebbero-scatenare-una-riacutizzazione\/","og_site_name":"Policlinico Universitario Agostino Gemelli IRCCS","article_modified_time":"2022-05-09T08:33:19+00:00","og_image":[{"url":"https:\/\/www.policlinicogemelli.it\/wp-content\/uploads\/2022\/05\/Giacomo-Sgalla-2.jpg","width":1024,"height":576,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.policlinicogemelli.it\/en\/news-events\/fibrosi-polmonare-idiopatica-vaccini-anti-covid-potrebbero-scatenare-una-riacutizzazione\/","url":"https:\/\/www.policlinicogemelli.it\/en\/news-events\/fibrosi-polmonare-idiopatica-vaccini-anti-covid-potrebbero-scatenare-una-riacutizzazione\/","name":"Fibrosi polmonare idiopatica, vaccini anti-Covid potrebbero scatenare una riacutizzazione - Policlinico Universitario A. Gemelli IRCCS","isPartOf":{"@id":"https:\/\/www.policlinicogemelli.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.policlinicogemelli.it\/en\/news-events\/fibrosi-polmonare-idiopatica-vaccini-anti-covid-potrebbero-scatenare-una-riacutizzazione\/#primaryimage"},"image":{"@id":"https:\/\/www.policlinicogemelli.it\/en\/news-events\/fibrosi-polmonare-idiopatica-vaccini-anti-covid-potrebbero-scatenare-una-riacutizzazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.policlinicogemelli.it\/wp-content\/uploads\/2022\/05\/Giacomo-Sgalla-2.jpg","datePublished":"2022-05-09T08:33:17+00:00","dateModified":"2022-05-09T08:33:19+00:00","breadcrumb":{"@id":"https:\/\/www.policlinicogemelli.it\/en\/news-events\/fibrosi-polmonare-idiopatica-vaccini-anti-covid-potrebbero-scatenare-una-riacutizzazione\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.policlinicogemelli.it\/en\/news-events\/fibrosi-polmonare-idiopatica-vaccini-anti-covid-potrebbero-scatenare-una-riacutizzazione\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.policlinicogemelli.it\/en\/news-events\/fibrosi-polmonare-idiopatica-vaccini-anti-covid-potrebbero-scatenare-una-riacutizzazione\/#primaryimage","url":"https:\/\/www.policlinicogemelli.it\/wp-content\/uploads\/2022\/05\/Giacomo-Sgalla-2.jpg","contentUrl":"https:\/\/www.policlinicogemelli.it\/wp-content\/uploads\/2022\/05\/Giacomo-Sgalla-2.jpg","width":4000,"height":2250},{"@type":"BreadcrumbList","@id":"https:\/\/www.policlinicogemelli.it\/en\/news-events\/fibrosi-polmonare-idiopatica-vaccini-anti-covid-potrebbero-scatenare-una-riacutizzazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.policlinicogemelli.it\/en\/"},{"@type":"ListItem","position":2,"name":"News and Events","item":"https:\/\/www.policlinicogemelli.it\/en\/news-events\/"},{"@type":"ListItem","position":3,"name":"Fibrosi polmonare idiopatica, vaccini anti-Covid potrebbero scatenare una riacutizzazione"}]},{"@type":"WebSite","@id":"https:\/\/www.policlinicogemelli.it\/en\/#website","url":"https:\/\/www.policlinicogemelli.it\/en\/","name":"Policlinico Universitario Agostino Gemelli IRCCS","description":"Policlinico Universitario Agostino Gemelli IRCCS","publisher":{"@id":"https:\/\/www.policlinicogemelli.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.policlinicogemelli.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.policlinicogemelli.it\/en\/#organization","name":"Policlinico Universitario Agostino Gemelli IRCCS","url":"https:\/\/www.policlinicogemelli.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.policlinicogemelli.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.policlinicogemelli.it\/wp-content\/uploads\/2019\/02\/logo-policlinico-gemelli-250-trasp-color-1.png","contentUrl":"https:\/\/www.policlinicogemelli.it\/wp-content\/uploads\/2019\/02\/logo-policlinico-gemelli-250-trasp-color-1.png","width":250,"height":82,"caption":"Policlinico Universitario Agostino Gemelli IRCCS"},"image":{"@id":"https:\/\/www.policlinicogemelli.it\/en\/#\/schema\/logo\/image\/"}}]}},"rest_api_enabler":[],"_links":{"self":[{"href":"https:\/\/www.policlinicogemelli.it\/en\/wp-json\/wp\/v2\/news\/44930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.policlinicogemelli.it\/en\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.policlinicogemelli.it\/en\/wp-json\/wp\/v2\/types\/kf_gem_news"}],"version-history":[{"count":0,"href":"https:\/\/www.policlinicogemelli.it\/en\/wp-json\/wp\/v2\/news\/44930\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.policlinicogemelli.it\/en\/wp-json\/wp\/v2\/media\/44928"}],"wp:attachment":[{"href":"https:\/\/www.policlinicogemelli.it\/en\/wp-json\/wp\/v2\/media?parent=44930"}],"wp:term":[{"taxonomy":"kf_gem_newscat","embeddable":true,"href":"https:\/\/www.policlinicogemelli.it\/en\/wp-json\/wp\/v2\/categorie?post=44930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}